{"id":404,"count":1,"description":"","link":"https:\/\/www.tonywhitehead.com\/wildlight\/archives\/tag\/skin-lesion","name":"skin lesion","slug":"skin-lesion","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>skin lesion Archives - WildLight Photography<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tonywhitehead.com\/wildlight\/archives\/tag\/skin-lesion\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"skin lesion Archives - WildLight Photography\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tonywhitehead.com\/wildlight\/archives\/tag\/skin-lesion\" \/>\n<meta property=\"og:site_name\" content=\"WildLight Photography\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.tonywhitehead.com\\\/wildlight\\\/archives\\\/tag\\\/skin-lesion\",\"url\":\"https:\\\/\\\/www.tonywhitehead.com\\\/wildlight\\\/archives\\\/tag\\\/skin-lesion\",\"name\":\"skin lesion Archives - WildLight Photography\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tonywhitehead.com\\\/wildlight\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tonywhitehead.com\\\/wildlight\\\/archives\\\/tag\\\/skin-lesion#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tonywhitehead.com\\\/wildlight\\\/archives\\\/tag\\\/skin-lesion#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tonywhitehead.com\\\/wildlight\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"skin lesion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tonywhitehead.com\\\/wildlight\\\/#website\",\"url\":\"https:\\\/\\\/www.tonywhitehead.com\\\/wildlight\\\/\",\"name\":\"WildLight Photography\",\"description\":\"Nature Photography by Tony Whitehead\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tonywhitehead.com\\\/wildlight\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"skin lesion Archives - WildLight Photography","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tonywhitehead.com\/wildlight\/archives\/tag\/skin-lesion","og_locale":"en_GB","og_type":"article","og_title":"skin lesion Archives - WildLight Photography","og_url":"https:\/\/www.tonywhitehead.com\/wildlight\/archives\/tag\/skin-lesion","og_site_name":"WildLight Photography","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.tonywhitehead.com\/wildlight\/archives\/tag\/skin-lesion","url":"https:\/\/www.tonywhitehead.com\/wildlight\/archives\/tag\/skin-lesion","name":"skin lesion Archives - WildLight Photography","isPartOf":{"@id":"https:\/\/www.tonywhitehead.com\/wildlight\/#website"},"breadcrumb":{"@id":"https:\/\/www.tonywhitehead.com\/wildlight\/archives\/tag\/skin-lesion#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tonywhitehead.com\/wildlight\/archives\/tag\/skin-lesion#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tonywhitehead.com\/wildlight\/"},{"@type":"ListItem","position":2,"name":"skin lesion"}]},{"@type":"WebSite","@id":"https:\/\/www.tonywhitehead.com\/wildlight\/#website","url":"https:\/\/www.tonywhitehead.com\/wildlight\/","name":"WildLight Photography","description":"Nature Photography by Tony Whitehead","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tonywhitehead.com\/wildlight\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.tonywhitehead.com\/wildlight\/wp-json\/wp\/v2\/tags\/404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tonywhitehead.com\/wildlight\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.tonywhitehead.com\/wildlight\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.tonywhitehead.com\/wildlight\/wp-json\/wp\/v2\/posts?tags=404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}